{"id":3614,"date":"2024-04-28T15:38:20","date_gmt":"2024-04-28T13:38:20","guid":{"rendered":"https:\/\/www.imtlazarus.com\/risorse-dei-partner\/"},"modified":"2026-06-03T12:59:55","modified_gmt":"2026-06-03T10:59:55","slug":"risorse-dei-partner","status":"publish","type":"page","link":"https:\/\/www.imtlazarus.com\/it\/risorse-dei-partner\/","title":{"rendered":"Risorse dei partner"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;wpt-divi-forms wpt-divi-forms wpt-divi-forms wpt-divi-forms wpt-divi-forms wpt-divi-forms wpt-divi-forms wpt-divi-forms&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;https:\/\/www.imtlazarus.com\/wp-content\/uploads\/blog-scaled.png&#8221; height=&#8221;410px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;off|off|off&#8221; module_class=&#8221;parent-section wpt-divi-forms wpt-divi-forms wpt-divi-forms wpt-divi-forms wpt-divi-forms wpt-divi-forms wpt-divi-forms wpt-divi-forms wpt-divi-forms wpt-divi-forms wpt-divi-forms wpt-divi-forms wpt-divi-forms&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;rgba(233,241,254,0.2)&#8221; background_image=&#8221;https:\/\/www.imtlazarus.com\/wp-content\/uploads\/Fondo-Hexagonos.png&#8221; parallax=&#8221;on&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;1em||||false|false&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; custom_padding=&#8221;||0px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_text=&#8221;Risorse per i partner&#8221; module_id=&#8221;btn_expand_row_1&#8243; module_class=&#8221;btn_row_toggle&#8221; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;32px&#8221; button_text_color=&#8221;#185abc&#8221; button_bg_color=&#8221;RGBA(255,255,255,0)&#8221; button_border_width=&#8221;0px&#8221; button_font=&#8221;|700|||||||&#8221; button_use_icon=&#8221;off&#8221; custom_padding=&#8221;25px|0px|25px|0px|false|true&#8221; custom_css_main_element=&#8221;width: 100%;&#8221; custom_css_after=&#8221;font-size: 30px !important;||line-height: 30px !important;||position: absolute;||right: 0px;||top: 0px;&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Arial||||||||&#8221; header_text_color=&#8221;#4f4f4f&#8221; header_font_size=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1><strong>Checklist di sicurezza <\/strong><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row module_class=&#8221;custom_expand_row expand_resources_partners&#8221; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;0em||3em||false|true&#8221; custom_padding=&#8221;|0em||0em|false|true&#8221; border_radii=&#8221;on|12px|12px|12px|12px&#8221; box_shadow_style=&#8221;preset2&#8243; box_shadow_color=&#8221;rgba(12,113,195,0.3)&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Arial|700|||||||&#8221; header_4_text_align=&#8221;left&#8221; header_4_text_color=&#8221;#777777&#8243; header_4_font_size=&#8221;20px&#8221; header_4_line_height=&#8221;2em&#8221; custom_margin=&#8221;3em|3em|3em|3em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><strong>Prepara la tua scuola per l&#8217;Intelligenza Artificiale<\/strong><\/h4>\n<p>L&#8217;IA \u00e8 gi\u00e0 nelle aule. Scarica la nostra <strong>Checklist di Implementazione Sicura<\/strong> e scopri come integrare questi strumenti garantendo il benessere digitale e il controllo del tuo ambiente educativo. <\/p>\n<p>&nbsp;<\/p>\n<div class=\"flex items-start gap-4\">\n<p style=\"display: flex; align-items: center; gap: 10px; margin-bottom: 15px;\"><span class=\"et-pb-icon\" style=\"font-size: 20px; color: #f7ce00; font-family: 'etmodules' !important; font-weight: 400; line-height: 1;\">Z<\/span><br \/>\n<span style=\"line-height: 1.5;\"><strong>Valutazione dei Rischi:<\/strong> Identifica e mitiga le minacce alla privacy e al cyberbullismo prima che si verifichino.<\/span><\/p>\n<p style=\"display: flex; align-items: center; gap: 10px; margin-bottom: 15px;\"><span class=\"et-pb-icon\" style=\"font-size: 20px; color: #f7ce00; font-family: 'etmodules' !important; font-weight: 400; line-height: 1;\">Z<\/span><br \/>\n<span style=\"line-height: 1.5;\"><strong>Politiche di Utilizzo:<\/strong> Crea normative chiare per studenti e insegnanti sull&#8217;uso etico dell&#8217;IA.<\/span><\/p>\n<p style=\"display: flex; align-items: center; gap: 10px; margin-bottom: 15px;\"><span class=\"et-pb-icon\" style=\"font-size: 20px; color: #f7ce00; font-family: 'etmodules' !important; font-weight: 400; line-height: 1;\">Z<\/span><br \/>\n<span style=\"line-height: 1.5;\"><strong>Filtraggio Intelligente:<\/strong> Scopri come IMTLazarus arriva dove il filtraggio tradizionale si ferma.<\/span><\/p>\n<hr>\n<p style=\"text-align: center;\"><span><\/span><\/p>\n<p style=\"text-align: center;\"><span>Proteggendo l&#8217;impronta digitale degli studenti. Conformit\u00e0 normativa garantita al 100%. <\/span><\/p>\n<\/div>\n<p>[\/et_pb_text][et_pb_button url_new_window=&#8221;on&#8221; button_text=&#8221;Scarica&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;15px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#741b47&#8243; button_border_radius=&#8221;8px&#8221; custom_margin=&#8221;||3em||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row module_class=&#8221;custom_expand_row expand_resources_partners&#8221; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;0em||3em||false|true&#8221; custom_padding=&#8221;|0em||0em|false|true&#8221; border_radii=&#8221;on|12px|12px|12px|12px&#8221; box_shadow_style=&#8221;preset2&#8243; box_shadow_color=&#8221;rgba(12,113,195,0.3)&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Arial|700|||||||&#8221; header_4_text_align=&#8221;left&#8221; header_4_text_color=&#8221;#777777&#8243; header_4_font_size=&#8221;20px&#8221; header_4_line_height=&#8221;2em&#8221; custom_margin=&#8221;3em|3em|0em|3em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>Perch\u00e9 \u00e8 fondamentale verificare l&#8217;IA nell&#8217;ambiente scolastico?<\/h4>\n<p>Mentre altri si limitano a chiudere la porta, in IMTLazarus controlliamo ci\u00f2 che accade dentro. Comprendi le sfide dell&#8217;IA per educare alla sicurezza. <\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_gallery gallery_ids=&#8221;5142,5157,5152,5147&#8243; orientation=&#8221;portrait&#8221; show_title_and_caption=&#8221;off&#8221; show_pagination=&#8221;off&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; width=&#8221;70%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||3em||false|false&#8221; link_option_url=&#8221;https:\/\/www.imtlazarus.com\/tecnologia\/&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_gallery][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Arial|700|||||||&#8221; header_4_text_align=&#8221;left&#8221; header_4_text_color=&#8221;#777777&#8243; header_4_font_size=&#8221;20px&#8221; header_4_line_height=&#8221;2em&#8221; custom_margin=&#8221;0em|0em|0em|0em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Scopri il contributo di ciascun agente all&#8217;IA e la loro interazione<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; module_class=&#8221;custom_expand_row expand_resources_partners&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; custom_margin=&#8221;0em||3em||false|true&#8221; custom_padding=&#8221;|0em||0em|false|true&#8221; border_radii=&#8221;on|12px|12px|12px|12px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;1em|1em|1em|1em|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Privacy del Minore&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf023;||fa||900&#8243; icon_color=&#8221;#FC9569&#8243; image_icon_background_color=&#8221;RGBA(255,255,255,0)&#8221; image_icon_width=&#8221;50px&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;|700|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#7f7f7f&#8221; header_font_size=&#8221;15px&#8221; background_color=&#8221;#FFFFFF&#8221; image_icon_custom_margin=&#8221;0.5em|5px|0.5em|0.4em|false|false&#8221; height=&#8221;300px&#8221; max_height=&#8221;300px&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;1.5em|2em|2em|2em|false|false&#8221; border_radii=&#8221;on|12px|12px|12px|12px&#8221; border_radii_image=&#8221;on|5px|5px|5px|5px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_color=&#8221;rgba(12,113,195,0.33)&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Gli strumenti di IA generativa raccolgono dati massivi. Impara a filtrare e configurare queste piattaforme affinch\u00e9 l&#8217;identit\u00e0 dei tuoi studenti sia protetta al 100%. <\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;1em|1em|1em|1em|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Benessere Digitale&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf3ed;||fa||900&#8243; icon_color=&#8221;#E09900&#8243; image_icon_background_color=&#8221;RGBA(255,255,255,0)&#8221; image_icon_width=&#8221;50px&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;|700|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#7f7f7f&#8221; header_font_size=&#8221;15px&#8221; background_color=&#8221;#FFFFFF&#8221; image_icon_custom_margin=&#8221;0.5em|5px|0.5em|0.4em|false|false&#8221; height=&#8221;300px&#8221; max_height=&#8221;300px&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;1.5em|2em|2em|2em|false|false&#8221; border_radii=&#8221;on|12px|12px|12px|12px&#8221; border_radii_image=&#8221;on|5px|5px|5px|5px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_color=&#8221;rgba(12,113,195,0.33)&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>L&#8217;IA pu\u00f2 potenziare la conoscenza, ma anche generare nuovi rischi. Rileva segnali di allarme tempestivamente nel comportamento digitale. <\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;1em|1em|1em|1em|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Controllo Intelligente&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf5dc;||fa||900&#8243; icon_color=&#8221;#F0B800&#8243; image_icon_background_color=&#8221;RGBA(255,255,255,0)&#8221; image_icon_width=&#8221;50px&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;|700|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#7f7f7f&#8221; header_font_size=&#8221;15px&#8221; background_color=&#8221;#FFFFFF&#8221; image_icon_custom_margin=&#8221;0.5em|5px|0.5em|0.4em|false|false&#8221; height=&#8221;300px&#8221; max_height=&#8221;300px&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;1.5em|2em|2em|2em|false|false&#8221; border_radii=&#8221;on|12px|12px|12px|12px&#8221; border_radii_image=&#8221;on|5px|5px|5px|5px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_color=&#8221;rgba(12,113,195,0.33)&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Integra l&#8217;IA per aiutare gli insegnanti, non per distrarre. Allinea l&#8217;uso delle nuove tecnologie con le politiche del tuo istituto. <\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row module_class=&#8221;custom_expand_row expand_resources_partners&#8221; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; custom_padding=&#8221;||||false|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Arial||||||||&#8221; header_text_color=&#8221;#4f4f4f&#8221; header_font_size=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1><b>Documentazione commerciale<\/b><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; module_class=&#8221;custom_expand_row expand_resources_partners&#8221; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;0em||3em||false|true&#8221; custom_padding=&#8221;|0em||0em|false|true&#8221; border_radii=&#8221;on|12px|12px|12px|12px&#8221; box_shadow_style=&#8221;preset2&#8243; box_shadow_color=&#8221;rgba(12,113,195,0.3)&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Arial|700|||||||&#8221; header_4_text_align=&#8221;left&#8221; header_4_text_color=&#8221;#777777&#8243; header_4_font_size=&#8221;15px&#8221; header_4_line_height=&#8221;2em&#8221; custom_margin=&#8221;3em||3em|3em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><a href=\"\/wp-content\/uploads\/ES-IMTLazarus-Presentacion-Corporativa.pdf\" target=\"_blank\" rel=\"noopener\">&#8211; Presentazione aziendale<\/a><\/h4>\n<h4 class=\"et_pb_module_header\"><a href=\"\/wp-content\/uploads\/ES-Integracion-microsoft-110324.pdf\" target=\"_blank\" rel=\"noopener\">&#8211; Integrazione di Microsoft Intune<\/a><\/h4>\n<h4><a href=\"\/wp-content\/uploads\/Preguntas-y-respuestas_ES-1.pdf\" target=\"_blank\" rel=\"noopener\">&#8211; Domande e risposte<\/a><\/h4>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Arial|700|||||||&#8221; header_4_text_align=&#8221;left&#8221; header_4_text_color=&#8221;#777777&#8243; header_4_font_size=&#8221;15px&#8221; header_4_line_height=&#8221;2em&#8221; custom_margin=&#8221;3em||3em|3em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><a href=\"\/wp-content\/uploads\/High-Five.pdf\" target=\"_blank\" rel=\"noopener\">&#8211; Principali funzionalit\u00e0<\/a><\/h4>\n<h4><a href=\"\/wp-content\/uploads\/ES-Integracion-Google-Workspace-110324.pdf\" target=\"_blank\" rel=\"noopener\">&#8211; Integrazione di Google Workspace<\/a><\/h4>\n<h4><a href=\"\/wp-content\/uploads\/Vision-y-ecosistema-1.6-ES.pdf\" target=\"_blank\" rel=\"noopener\">&#8211; Visione ed ecosistema<\/a><\/h4>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Arial|700|||||||&#8221; header_4_text_align=&#8221;left&#8221; header_4_text_color=&#8221;#777777&#8243; header_4_font_size=&#8221;15px&#8221; header_4_line_height=&#8221;2em&#8221; custom_margin=&#8221;3em||3em|3em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><a href=\"\/wp-content\/uploads\/Funcionalidades_V1.7-ES-3.pdf\" target=\"_blank\" rel=\"noopener\">&#8211; Funzionalit\u00e0 per licenza<\/a><\/h4>\n<h4><a href=\"\/wp-content\/uploads\/ES-Integracion-Apple-110324.pdf\" target=\"_blank\" rel=\"noopener\">&#8211; Integrazione con Apple education<\/a><\/h4>\n<h4><a href=\"\/wp-content\/uploads\/IMTHome-control-familiar.pdf\" target=\"_blank\" rel=\"noopener\" title=\"IMTHome controllo familiare\">&#8211; IMTHome controllo familiare<\/a><\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Arial||||||||&#8221; header_text_color=&#8221;#4f4f4f&#8221; header_font_size=&#8221;25px&#8221; custom_padding=&#8221;1px|||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1><b>Documentazione del distributore<\/b><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; module_class=&#8221;custom_expand_row expand_resources_partners&#8221; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;0em||3em||false|true&#8221; custom_padding=&#8221;|0em||0em|false|true&#8221; border_radii=&#8221;on|12px|12px|12px|12px&#8221; box_shadow_style=&#8221;preset2&#8243; box_shadow_color=&#8221;rgba(12,113,195,0.3)&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Arial|700|||||||&#8221; header_4_text_align=&#8221;left&#8221; header_4_text_color=&#8221;#777777&#8243; header_4_font_size=&#8221;15px&#8221; header_4_line_height=&#8221;2em&#8221; custom_margin=&#8221;3em||3em|3em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><a href=\"https:\/\/www.imtlazarus.com\/wp-content\/uploads\/Condiciones-de-Servicio-Cloud-IMTLazarus_ES-1.pdf\" target=\"_blank\" rel=\"noopener\">&#8211; Servizio cloud<\/a><\/h4>\n<h4 class=\"et_pb_module_header\"><a href=\"https:\/\/www.imtlazarus.com\/wp-content\/uploads\/MOD_CONTRATODISTRIBUIDOR_V6.2_GetAccept.ES_.pdf\" target=\"_blank\" rel=\"noopener\">&#8211; Accordo commerciale distributore<\/a><\/h4>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Arial|700|||||||&#8221; header_4_text_align=&#8221;left&#8221; header_4_text_color=&#8221;#777777&#8243; header_4_font_size=&#8221;15px&#8221; header_4_line_height=&#8221;2em&#8221; custom_margin=&#8221;3em||3em|3em|false|false&#8221; link_option_url=&#8221;\/wp-content\/uploads\/Politica-General-1.1_ES.pdf&#8221; link_option_url_new_window=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><a href=\"https:\/\/www.imtlazarus.com\/wp-content\/uploads\/TerminosCondicionesPagoMayo26-1.pdf\" target=\"_blank\" rel=\"noopener\" title=\"https:\/\/www.imtlazarus.com\/wp-content\/uploads\/TerminosCondicionesPagoMayo26-1.pdf\">&#8211; Termini e condizioni di pagamento<\/a><\/h4>\n<h4><a href=\"https:\/\/www.imtlazarus.com\/wp-content\/uploads\/Politica-General_ES-1.pdf\" target=\"_blank\" rel=\"noopener\">&#8211; Politica generale<\/a><\/h4>\n<h4><\/h4>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Arial|700|||||||&#8221; header_4_text_align=&#8221;left&#8221; header_4_text_color=&#8221;#777777&#8243; header_4_font_size=&#8221;15px&#8221; header_4_line_height=&#8221;2em&#8221; custom_margin=&#8221;3em||3em|3em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><a href=\"https:\/\/www.imtlazarus.com\/wp-content\/uploads\/Requisitos-tecnicos-IMTLazarus_ES.pdf\" target=\"_blank\" rel=\"noopener\">&#8211; Requisiti tecnici<\/a><\/h4>\n<h4><a href=\"\/wp-content\/uploads\/Diagrama-de-flujo-para-despliegue.pdf\" target=\"_blank\" rel=\"noopener\">&#8211; Diagramma di flusso di dispiegamento<\/a><\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Arial||||||||&#8221; header_text_color=&#8221;#4f4f4f&#8221; header_font_size=&#8221;25px&#8221; custom_padding=&#8221;9px|||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1><strong><span>Prezzi licenze servizio<\/span><\/strong><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; module_class=&#8221;custom_expand_row expand_resources_partners&#8221; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;0em||3em||false|true&#8221; custom_padding=&#8221;|0em||0em|false|true&#8221; border_radii=&#8221;on|12px|12px|12px|12px&#8221; box_shadow_style=&#8221;preset2&#8243; box_shadow_color=&#8221;rgba(12,113,195,0.3)&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Arial|700|||||||&#8221; header_4_text_align=&#8221;left&#8221; header_4_text_color=&#8221;#777777&#8243; header_4_font_size=&#8221;15px&#8221; header_4_line_height=&#8221;2em&#8221; custom_margin=&#8221;3em||3em|3em|false|false&#8221; link_option_url=&#8221;https:\/\/www.imtlazarus.com\/wp-content\/uploads\/ES-EU-Level-of-licenses-v1.6.pdf&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><strong><a href=\"https:\/\/www.imtlazarus.com\/wp-content\/uploads\/Licencias-2026-ES-.pdf\" target=\"_blank\" rel=\"noopener\" title=\"Prezzo annuale licenze Spagna\">&#8211; Prezzo annuale licenze IT<\/a><\/strong><\/h4>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Arial|700|||||||&#8221; header_4_text_align=&#8221;left&#8221; header_4_text_color=&#8221;#777777&#8243; header_4_font_size=&#8221;15px&#8221; header_4_line_height=&#8221;2em&#8221; custom_margin=&#8221;3em||3em|3em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><a href=\"https:\/\/www.imtlazarus.com\/wp-content\/uploads\/Licencias-INTUSA-2026-EN-.pdf\" target=\"_blank\" rel=\"noopener\" title=\"Prezzo annuale licenze istruzione INT e USA\">&#8211; Prezzo annuale licenze INT e USA<\/a><\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Arial||||||||&#8221; header_text_color=&#8221;#4f4f4f&#8221; header_font_size=&#8221;25px&#8221; custom_padding=&#8221;9px|||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1><strong><span>Guide all&#8217;installazione e all&#8217;uso<\/span><\/strong><\/h1>\n<h1><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; module_class=&#8221;custom_expand_row expand_resources_partners&#8221; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;0em||3em||false|true&#8221; custom_padding=&#8221;|0em||0em|false|true&#8221; border_radii=&#8221;on|12px|12px|12px|12px&#8221; box_shadow_style=&#8221;preset2&#8243; box_shadow_color=&#8221;rgba(12,113,195,0.3)&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Arial|700|||||||&#8221; header_4_text_align=&#8221;left&#8221; header_4_text_color=&#8221;#777777&#8243; header_4_font_size=&#8221;15px&#8221; header_4_line_height=&#8221;2em&#8221; custom_margin=&#8221;3em||3em|3em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><a href=\"https:\/\/www.imtlazarus.com\/wp-content\/uploads\/20260325-Carga-de-extension-IMTLazarus-en-Google-Workspace-ES.pdf\" target=\"_blank\" rel=\"noopener\" title=\"Carica estensione Google Workspace\">&#8211; Carica estensione di Google Workspace<\/a><\/h4>\n<h4 class=\"et_pb_module_header\"><a href=\"https:\/\/www.imtlazarus.com\/wp-content\/uploads\/Validar-acceso-Microsoft-01042026-1.pdf\" target=\"_blank\" rel=\"noopener\">&#8211; Convalida l&#8217;accesso Microsoft<\/a><\/h4>\n<h4><a href=\"\/wp-content\/uploads\/IMTLazarus-Integracion-Google-Classroom-ES-20250917.pdf\" target=\"_blank\" rel=\"noopener\">&#8211; Integrazione di Google Classroom<\/a><\/h4>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Arial|700|||||||&#8221; header_4_text_align=&#8221;left&#8221; header_4_text_color=&#8221;#777777&#8243; header_4_font_size=&#8221;15px&#8221; header_4_line_height=&#8221;2em&#8221; custom_margin=&#8221;3em||3em|3em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><a href=\"https:\/\/www.imtlazarus.com\/wp-content\/uploads\/20260324-Importacion-de-datos-desde-Google-Workspace-ES.pdf\" target=\"_blank\" rel=\"noopener\">&#8211; Importazione di dati da Google Workspace<\/a><\/h4>\n<h4><a href=\"\/wp-content\/uploads\/Despliegue-de-IMTLazarus-a-traves-de-Intune.pdf\" target=\"_blank\" rel=\"noopener\">&#8211; Distribuzione tramite Intune<\/a><\/h4>\n<h4><a href=\"\/wp-content\/uploads\/Guia-Instalacion-Android-MDM-20251201-ES-1.pdf\" target=\"_blank\" rel=\"noopener\">&#8211; Guida all&#8217;installazione di Android MDM<\/a><\/h4>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Arial|700|||||||&#8221; header_4_text_align=&#8221;left&#8221; header_4_text_color=&#8221;#777777&#8243; header_4_font_size=&#8221;15px&#8221; header_4_line_height=&#8221;2em&#8221; custom_margin=&#8221;3em|3em|3em|3em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><a href=\"https:\/\/www.imtlazarus.com\/wp-content\/uploads\/Guia-instalacion-Android_ES-1.pdf\" target=\"_blank\" rel=\"noopener\">&#8211; Guida di installazione di Android<\/a><\/h4>\n<h4><a href=\"\/wp-content\/uploads\/Integracion-de-dispositivos-Apple-macOS-en-IMTLazarus-010223.pdf\" target=\"_blank\" rel=\"noopener\" title=\"Integrazione di dispositivi Apple e Mac\">&#8211; Integrazione dispositivi Apple e Mac<\/a><\/h4>\n<h4><a href=\"\/wp-content\/uploads\/Manual-de-integracion-IMTLazarus-con-Microsoft-Azure-ES.pdf\" target=\"_blank\" rel=\"noopener\">&#8211; Integrazione con Microsoft Azure<\/a><\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Arial||||||||&#8221; header_text_color=&#8221;#4f4f4f&#8221; header_font_size=&#8221;25px&#8221; custom_padding=&#8221;9px|||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1><strong><span>Guide interattive<\/span><\/strong><\/h1>\n<h1><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; module_class=&#8221;custom_expand_row expand_resources_partners&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;0em||3em||false|true&#8221; custom_padding=&#8221;|0em||0em|false|true&#8221; border_radii=&#8221;on|12px|12px|12px|12px&#8221; box_shadow_style=&#8221;preset2&#8243; box_shadow_color=&#8221;rgba(12,113,195,0.3)&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Arial|700|||||||&#8221; header_4_text_align=&#8221;left&#8221; header_4_text_color=&#8221;#777777&#8243; header_4_font_size=&#8221;15px&#8221; header_4_line_height=&#8221;2em&#8221; custom_margin=&#8221;3em||3em|3em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><a href=\"https:\/\/www.imtlazarus.com\/it\/guida-interattiva-google\/\" title=\"- Guida interattiva Google\">&#8211; Guida interattiva Google<\/a><\/h4>\n<h4><a href=\"https:\/\/www.imtlazarus.com\/it\/guida-interattiva-ios\/\">&#8211; Guida interattiva iOS<\/a><\/h4>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;Arial|700|||||||&#8221; header_4_text_align=&#8221;left&#8221; header_4_text_color=&#8221;#777777&#8243; header_4_font_size=&#8221;15px&#8221; header_4_line_height=&#8221;2em&#8221; custom_margin=&#8221;3em||3em|3em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><a href=\"https:\/\/www.imtlazarus.com\/guia-interactiva-azure\/\" title=\"- Guida interattiva Windows\">&#8211; Guida interattiva Windows<\/a><\/h4>\n<h4><a href=\"https:\/\/www.imtlazarus.com\/guia-interactiva-android\/\" title=\"- Guida interattiva Android\">&#8211; Guida interattiva Android<\/a><\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Arial||||||||&#8221; header_text_color=&#8221;#4f4f4f&#8221; header_font_size=&#8221;25px&#8221; custom_padding=&#8221;9px|||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1><strong>Certificazione partner<\/strong><\/h1>\n<h1><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;0em||3em||false|true&#8221; custom_padding=&#8221;|0em||0em|false|true&#8221; border_radii=&#8221;on|12px|12px|12px|12px&#8221; box_shadow_style=&#8221;preset2&#8243; box_shadow_color=&#8221;rgba(12,113,195,0.3)&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;3em|3em|1em|3em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>Il programma di certificazione \u00e8 organizzato in una scala di valore crescente, dove <\/span><strong>l&#8217;esclusivit\u00e0 \u00e8 il fattore determinante<\/strong><span> per accedere ai maggiori benefici. I livelli del programma sono Standard, Avanzato e Premium.<\/span><span><\/span><\/p>\n<h4><strong>Vantaggi per livello<\/strong><\/h4>\n<p><!-- Tabla Comparativa --><\/p>\n<p>[\/et_pb_text][et_pb_code _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;1em|3em|3em|3em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<style><!-- [et_pb_line_break_holder] -->  \/* Contenedor principal *\/<!-- [et_pb_line_break_holder] -->  .imtl-wrapper {<!-- [et_pb_line_break_holder] -->    font-family: inherit;<!-- [et_pb_line_break_holder] -->    color: #334155;<!-- [et_pb_line_break_holder] -->    line-height: 1.6;<!-- [et_pb_line_break_holder] -->    max-width: 1200px;<!-- [et_pb_line_break_holder] -->    margin: 0 auto;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  \/* T\u00edtulo de la secci\u00f3n *\/<!-- [et_pb_line_break_holder] -->  .imtl-title {<!-- [et_pb_line_break_holder] -->    font-size: 1.75rem;<!-- [et_pb_line_break_holder] -->    color: #1e293b;<!-- [et_pb_line_break_holder] -->    margin-bottom: 24px;<!-- [et_pb_line_break_holder] -->    text-align: center;<!-- [et_pb_line_break_holder] -->    font-weight: 700;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  \/* Tabla comparativa responsiva *\/<!-- [et_pb_line_break_holder] -->  .imtl-table-container {<!-- [et_pb_line_break_holder] -->    overflow-x: auto;<!-- [et_pb_line_break_holder] -->    margin-bottom: 20px;<!-- [et_pb_line_break_holder] -->    box-shadow: 0 4px 6px -1px rgba(0, 0, 0, 0.1);<!-- [et_pb_line_break_holder] -->    border-radius: 8px;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  .imtl-table {<!-- [et_pb_line_break_holder] -->    width: 100%;<!-- [et_pb_line_break_holder] -->    border-collapse: collapse;<!-- [et_pb_line_break_holder] -->    min-width: 800px; \/* Asegura el scroll en m\u00f3viles para no aplastar el texto *\/<!-- [et_pb_line_break_holder] -->    background: #ffffff;<!-- [et_pb_line_break_holder] -->    text-align: left;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  .imtl-table th, .imtl-table td {<!-- [et_pb_line_break_holder] -->    padding: 16px;<!-- [et_pb_line_break_holder] -->    border-bottom: 1px solid #e2e8f0;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  .imtl-table th.imtl-th-title {<!-- [et_pb_line_break_holder] -->    font-weight: 600;<!-- [et_pb_line_break_holder] -->    color: #ffffff !important; \/* Fuerza el color blanco sobre los estilos de Divi *\/<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  \/* Colores de las cabeceras *\/<!-- [et_pb_line_break_holder] -->  .imtl-table th:first-child { background-color: #334155; width: 25%; } \/* Beneficio *\/<!-- [et_pb_line_break_holder] -->  .imtl-table th:nth-child(2) { background-color: #b45309; width: 25%; } \/* Est\u00e1ndar *\/<!-- [et_pb_line_break_holder] -->  .imtl-table th:nth-child(3) { background-color: #64748b; width: 25%; } \/* Avanzado *\/<!-- [et_pb_line_break_holder] -->  .imtl-table th:nth-child(4) { background-color: #ca8a04; width: 25%; } \/* Premium *\/<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  .imtl-table tr:last-child td {<!-- [et_pb_line_break_holder] -->    border-bottom: none;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  \/* Efecto hover al pasar el rat\u00f3n *\/<!-- [et_pb_line_break_holder] -->  .imtl-table tr:hover {<!-- [et_pb_line_break_holder] -->    background-color: #f8fafc;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  \/* Estilo para la primera columna (nombres de los beneficios) *\/<!-- [et_pb_line_break_holder] -->  .imtl-table td:first-child {<!-- [et_pb_line_break_holder] -->    font-weight: 600;<!-- [et_pb_line_break_holder] -->    color: #0f172a;<!-- [et_pb_line_break_holder] -->    background-color: #f8fafc;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><\/style>\n<p><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><\/p>\n<div class=\"imtl-wrapper\"><!-- [et_pb_line_break_holder] -->  <\/p>\n<div class=\"imtl-table-container\"><!-- [et_pb_line_break_holder] -->    <\/p>\n<table class=\"imtl-table\"><!-- [et_pb_line_break_holder] -->      <\/p>\n<thead><!-- [et_pb_line_break_holder] -->        <\/p>\n<tr><!-- [et_pb_line_break_holder] -->          <\/p>\n<th class=\"imtl-th-title\">Vantaggio<\/th>\n<p><!-- [et_pb_line_break_holder] -->          <\/p>\n<th class=\"imtl-th-title\">\ud83e\udd49 Standard<\/th>\n<p><!-- [et_pb_line_break_holder] -->          <\/p>\n<th class=\"imtl-th-title\">\ud83e\udd48 Avanzato<\/th>\n<p><!-- [et_pb_line_break_holder] -->          <\/p>\n<th class=\"imtl-th-title\">\ud83e\udd47 Premium (Esclusivo)<\/th>\n<p><!-- [et_pb_line_break_holder] -->        <\/tr>\n<p><!-- [et_pb_line_break_holder] -->      <\/thead>\n<p><!-- [et_pb_line_break_holder] -->      <\/p>\n<tbody><!-- [et_pb_line_break_holder] -->        <\/p>\n<tr><!-- [et_pb_line_break_holder] -->          <\/p>\n<td>Licenze Consentite<\/td>\n<p><!-- [et_pb_line_break_holder] -->          <\/p>\n<td>Standard o inferiori<\/td>\n<p><!-- [et_pb_line_break_holder] -->          <\/p>\n<td>Fino a licenza Plus<\/td>\n<p><!-- [et_pb_line_break_holder] -->          <\/p>\n<td>Tutte, inclusa Premium<\/td>\n<p><!-- [et_pb_line_break_holder] -->        <\/tr>\n<p><!-- [et_pb_line_break_holder] -->        <\/p>\n<tr><!-- [et_pb_line_break_holder] -->          <\/p>\n<td>Margine Commerciale<\/td>\n<p><!-- [et_pb_line_break_holder] -->          <\/p>\n<td>Base<\/td>\n<p><!-- [et_pb_line_break_holder] -->          <\/p>\n<td>Migliorato<\/td>\n<p><!-- [et_pb_line_break_holder] -->          <\/p>\n<td>Massimo<\/td>\n<p><!-- [et_pb_line_break_holder] -->        <\/tr>\n<p><!-- [et_pb_line_break_holder] -->        <\/p>\n<tr><!-- [et_pb_line_break_holder] -->          <\/p>\n<td>Protezione Lead<\/td>\n<p><!-- [et_pb_line_break_holder] -->          <\/p>\n<td>30 giorni (base)<\/td>\n<p><!-- [et_pb_line_break_holder] -->          <\/p>\n<td>60 giorni (priorit\u00e0 media)<\/td>\n<p><!-- [et_pb_line_break_holder] -->          <\/p>\n<td>Senza condizioni rispetto ai livelli inferiori<\/td>\n<p><!-- [et_pb_line_break_holder] -->        <\/tr>\n<p><!-- [et_pb_line_break_holder] -->        <\/p>\n<tr><!-- [et_pb_line_break_holder] -->          <\/p>\n<td>Fondi Marketing<\/td>\n<p><!-- [et_pb_line_break_holder] -->          <\/p>\n<td>Non disponibile<\/td>\n<p><!-- [et_pb_line_break_holder] -->          <\/p>\n<td>Soggetto ad approvazione del piano<\/td>\n<p><!-- [et_pb_line_break_holder] -->          <\/p>\n<td>Fino al 5% del fatturato annuale dell&#8217;esercizio precedente<\/td>\n<p><!-- [et_pb_line_break_holder] -->        <\/tr>\n<p><!-- [et_pb_line_break_holder] -->      <\/tbody>\n<p><!-- [et_pb_line_break_holder] -->    <\/table>\n<p><!-- [et_pb_line_break_holder] -->  <\/div>\n<p><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><\/div>\n<p><!-- [et_pb_line_break_holder] --><script><!-- [et_pb_line_break_holder] -->(function ($) {<!-- [et_pb_line_break_holder] -->  $(document).ready(function () {<!-- [et_pb_line_break_holder] --> <!-- [et_pb_line_break_holder] -->    \/\/ Option #1: Move Divi Module(s) into a Module<!-- [et_pb_line_break_holder] -->    \/\/ Limit: One Instance per Column<!-- [et_pb_line_break_holder] -->    \/\/ Use following code if you want to move <!-- [et_pb_line_break_holder] -->    \/\/ a module inside another module. Each column with the<!-- [et_pb_line_break_holder] -->    \/\/ class 'parent-column' will append any module(s)<!-- [et_pb_line_break_holder] -->    \/\/ with the class 'divi-portable-module' to the div<!-- [et_pb_line_break_holder] -->    \/\/ with the class 'divi-module-destination'.<!-- [et_pb_line_break_holder] -->    \/\/ Only one instance of 'divi-module-destination' should<!-- [et_pb_line_break_holder] -->    \/\/ be added per column.<!-- [et_pb_line_break_holder] -->    $('.divi-portable-advert001').each(function () {<!-- [et_pb_line_break_holder] -->      $(this).closest('.divi-portable-row1-1').find('.divi-module-filtnav').append($(this));<!-- [et_pb_line_break_holder] -->    });<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->    \/\/ Buttons: Insert Button Module(s) into a Module<!-- [et_pb_line_break_holder] -->    \/\/ Adding a custom CSS class to a button module<!-- [et_pb_line_break_holder] -->    \/\/ is applied to the 'a' tag which is a child element<!-- [et_pb_line_break_holder] -->    \/\/ of the module wrapper. This code makes sure to append<!-- [et_pb_line_break_holder] -->    \/\/ the entire button module wrapper (the parent element)<!-- [et_pb_line_break_holder] -->    \/\/ as well. This functionality is the same as option #3 above.<!-- [et_pb_line_break_holder] -->    \/\/ Siimply use the class 'divi-portable-button' on a button module<!-- [et_pb_line_break_holder] -->    \/\/ instead of 'divi-portable-module'.<!-- [et_pb_line_break_holder] -->    $('.divi-portable-button').parent().each(function () {<!-- [et_pb_line_break_holder] -->      $(this).closest('.parent-column').find('.divi-module-destination').append($(this));<!-- [et_pb_line_break_holder] -->    });<!-- [et_pb_line_break_holder] --> <!-- [et_pb_line_break_holder] -->    \/\/ Option #2: Move Divi Row(s) into a Module<!-- [et_pb_line_break_holder] -->    \/\/ Limit: One Instance per Section<!-- [et_pb_line_break_holder] -->    \/\/ Use the following code if you want to move <!-- [et_pb_line_break_holder] -->    \/\/ a row inside a module on more than one section<!-- [et_pb_line_break_holder] -->    \/\/ of a page. Each section with the<!-- [et_pb_line_break_holder] -->    \/\/ class 'parent-section' will append any row(s)<!-- [et_pb_line_break_holder] -->    \/\/ with the class 'divi-portable-row' to the div<!-- [et_pb_line_break_holder] -->    \/\/ with the class 'divi-row-destination'.<!-- [et_pb_line_break_holder] -->    \/\/ Only one instance of 'divi-row-destination' should<!-- [et_pb_line_break_holder] -->    \/\/ be added per section.<!-- [et_pb_line_break_holder] -->    $('.divi-portable-row1').each(function () {<!-- [et_pb_line_break_holder] -->      $(this).closest('.parent-section').find('.divi-row-destination1').append($(this));<!-- [et_pb_line_break_holder] -->    });<!-- [et_pb_line_break_holder] -->    $('.divi-portable-row2').each(function () {<!-- [et_pb_line_break_holder] -->      $(this).closest('.parent-section').find('.divi-row-destination2').append($(this));<!-- [et_pb_line_break_holder] -->    });  <!-- [et_pb_line_break_holder] -->  });<!-- [et_pb_line_break_holder] -->})(jQuery);<!-- [et_pb_line_break_holder] --><\/script>[\/et_pb_code][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;3em|3em|1em|3em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><strong>Caratteristiche dei Livelli di Certificazione<\/strong><\/h4>\n<p><!-- Tabla Comparativa --><\/p>\n<div class=\"divi-row-destination1\"><\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; admin_label=&#8221;caratteristiche livelli&#8221; module_class=&#8221;divi-portable-row1&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; custom_margin=&#8221;2em||||false|false&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;2em|0px|2em|0px|false|false&#8221; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_top=&#8221;6px&#8221; border_color_top=&#8221;#c15c09&#8243; border_width_right=&#8221;1px&#8221; border_color_right=&#8221;rgba(165,165,165,0.66)&#8221; border_width_bottom=&#8221;1px&#8221; border_color_bottom=&#8221;rgba(165,165,165,0.66)&#8221; border_width_left=&#8221;1px&#8221; border_color_left=&#8221;rgba(165,165,165,0.66)&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;3px&#8221; box_shadow_blur=&#8221;66px&#8221; box_shadow_spread=&#8221;-46px&#8221; box_shadow_color=&#8221;#0C71C3&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.imtlazarus.com\/wp-content\/uploads\/sello-partner-estandard.png&#8221; title_text=&#8221;sigillo partner standard&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;50%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;2em|2em|2em|2em|false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;|2em||2em|false|false&#8221; custom_css_free_form=&#8221;||  .mi-lista-divi ul { list-style: none; padding: 0; margin: 20px 0 0 0; }||  .mi-lista-divi li { display: flex; align-items: center; margin-bottom: 12px; font-size: 14px; color: #333; }||  .mi-lista-divi svg { width: 18px; height: 18px; margin-right: 10px; flex-shrink: 0; }||  .check-icon { fill: #111827; }||  .cross-icon { fill: #9ca3af; color: #9ca3af; }||  .item-disabled { color: #9ca3af; text-decoration: line-through; text-decoration-color: transparent; } \/* Opcional: tachado *\/&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><b>Livello Standard<br \/><\/b><\/h2>\n<p><b><span>Acquisizione e Formazione<\/span><\/b><\/p>\n<p><b><\/b>Questo livello funziona come punto di ingresso per aziende IT che commercializzano molteplici soluzioni e stanno iniziando la loro relazione con IMTLazarus.<\/p>\n<p>[\/et_pb_text][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x5c;||divi||400&#8243; icon_color=&#8221;#0c71c3&#8243; image_icon_background_color=&#8221;#FFFFFF&#8221; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;15px&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; body_line_height=&#8221;1.2em&#8221; image_icon_custom_margin=&#8221;2em||2em|1em|false|false&#8221; custom_padding=&#8221;|2em||0.5em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Focus: <\/strong>Autonomia del partner attraverso formazione <em data-prosemirror-content-type=\"mark\" data-prosemirror-mark-name=\"em\">on-demand<\/em> e materiali di marketing generici (schede tecniche personalizzabili con logo).<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x5c;||divi||400&#8243; icon_color=&#8221;#0c71c3&#8243; image_icon_background_color=&#8221;#FFFFFF&#8221; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;15px&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; body_line_height=&#8221;1.2em&#8221; image_icon_custom_margin=&#8221;2em||2em|1em|false|false&#8221; custom_padding=&#8221;|2em||0.5em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Riconoscimento:<\/strong> Inclusione base nella directory web e uso di badge digitali &#8220;IMTLazarus Certified&#8221; per generare fiducia nella scuola.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x5c;||divi||400&#8243; icon_color=&#8221;#0c71c3&#8243; image_icon_background_color=&#8221;#FFFFFF&#8221; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;15px&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; body_line_height=&#8221;1.2em&#8221; image_icon_custom_margin=&#8221;2em||2em|1em|false|false&#8221; custom_padding=&#8221;|2em||0.5em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Strumenti:<\/strong> Accesso a &#8220;Battlecard&#8221; competitive per evidenziare i punti di forza della soluzione nel settore K-12.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;2em|0px|2em|0px|false|false&#8221; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_top=&#8221;6px&#8221; border_color_top=&#8221;#64748b&#8221; border_width_right=&#8221;1px&#8221; border_color_right=&#8221;rgba(165,165,165,0.66)&#8221; border_width_bottom=&#8221;1px&#8221; border_color_bottom=&#8221;rgba(165,165,165,0.66)&#8221; border_width_left=&#8221;1px&#8221; border_color_left=&#8221;rgba(165,165,165,0.66)&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;3px&#8221; box_shadow_blur=&#8221;66px&#8221; box_shadow_spread=&#8221;-46px&#8221; box_shadow_color=&#8221;#0C71C3&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.imtlazarus.com\/wp-content\/uploads\/sello-partner-avanzado.png&#8221; title_text=&#8221;sigillo partner avanzato&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;50%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;2em|2em|2em|2em|false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|2em||2em|false|false&#8221; custom_css_free_form=&#8221;||  .mi-lista-divi ul { list-style: none; padding: 0; margin: 20px 0 0 0; }||  .mi-lista-divi li { display: flex; align-items: center; margin-bottom: 12px; font-size: 14px; color: #333; }||  .mi-lista-divi svg { width: 18px; height: 18px; margin-right: 10px; flex-shrink: 0; }||  .check-icon { fill: #111827; }||  .cross-icon { fill: #9ca3af; color: #9ca3af; }||  .item-disabled { color: #9ca3af; text-decoration: line-through; text-decoration-color: transparent; } \/* Opcional: tachado *\/&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><b>Livello Avanzato<br \/><\/b><\/h2>\n<p><b><\/b><strong>Crescita e Specializzazione. <\/strong><\/p>\n<p>Rivolto a partner con vendite ricorrenti che cercano di consolidarsi nel mercato senza esclusivit\u00e0 totale.<\/p>\n<p>[\/et_pb_text][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x5c;||divi||400&#8243; icon_color=&#8221;#0c71c3&#8243; image_icon_background_color=&#8221;#FFFFFF&#8221; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;15px&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; body_line_height=&#8221;1.2em&#8221; image_icon_custom_margin=&#8221;2em||2em|1em|false|false&#8221; custom_padding=&#8221;|2em||0.5em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Supporto nelle Gare:<\/strong> Assistenza diretta del team prevendita per la redazione di capitolati tecnici in gare pubbliche o grandi gruppi privati.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x5c;||divi||400&#8243; icon_color=&#8221;#0c71c3&#8243; image_icon_background_color=&#8221;#FFFFFF&#8221; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;15px&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; body_line_height=&#8221;1.2em&#8221; image_icon_custom_margin=&#8221;2em||2em|1em|false|false&#8221; custom_padding=&#8221;|2em||0.5em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Riduzione degli Attriti:<\/strong> Voucher per certificazioni tecniche gratuite e accesso a programmi beta per testare nuove funzionalit\u00e0 con scuole di fiducia.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;2em|0px|2em|0px|false|false&#8221; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_top=&#8221;6px&#8221; border_color_top=&#8221;#ca8a04&#8243; border_width_right=&#8221;1px&#8221; border_color_right=&#8221;rgba(165,165,165,0.66)&#8221; border_width_bottom=&#8221;1px&#8221; border_color_bottom=&#8221;rgba(165,165,165,0.66)&#8221; border_width_left=&#8221;1px&#8221; border_color_left=&#8221;rgba(165,165,165,0.66)&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;3px&#8221; box_shadow_blur=&#8221;66px&#8221; box_shadow_spread=&#8221;-46px&#8221; box_shadow_color=&#8221;#0C71C3&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.imtlazarus.com\/wp-content\/uploads\/Sello-partner-Premium.png&#8221; title_text=&#8221;Sigillo partner Premium&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;50%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;2em|2em|2em|2em|false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|2em||2em|false|false&#8221; custom_css_free_form=&#8221;||  .mi-lista-divi ul { list-style: none; padding: 0; margin: 20px 0 0 0; }||  .mi-lista-divi li { display: flex; align-items: center; margin-bottom: 12px; font-size: 14px; color: #333; }||  .mi-lista-divi svg { width: 18px; height: 18px; margin-right: 10px; flex-shrink: 0; }||  .check-icon { fill: #111827; }||  .cross-icon { fill: #9ca3af; color: #9ca3af; }||  .item-disabled { color: #9ca3af; text-decoration: line-through; text-decoration-color: transparent; } \/* Opcional: tachado *\/&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><b>Livello Premium<br \/><\/b><\/h2>\n<p><b><\/b><strong>Redditivit\u00e0 VIP ed Esclusivit\u00e0. <\/strong><\/p>\n<p>Questo livello \u00e8 aspirazionale ed \u00e8 riservato ai partner che agiscono come un&#8217;estensione di IMTLazarus, rinunciando a commercializzare soluzioni della concorrenza.<\/p>\n<p>[\/et_pb_text][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x5c;||divi||400&#8243; icon_color=&#8221;#0c71c3&#8243; image_icon_background_color=&#8221;#FFFFFF&#8221; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;15px&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; body_line_height=&#8221;1.2em&#8221; image_icon_custom_margin=&#8221;2em||2em|1em|false|false&#8221; custom_padding=&#8221;|2em||0.5em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Esclusivit\u00e0 di prodotto:<\/strong> Solo i partner Premium possono vendere la &#8220;Licenza Premium&#8221; e gestire condizioni speciali per grandi gruppi educativi (congregazioni, fondazioni).<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x5c;||divi||400&#8243; icon_color=&#8221;#0c71c3&#8243; image_icon_background_color=&#8221;#FFFFFF&#8221; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;15px&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; body_line_height=&#8221;1.2em&#8221; image_icon_custom_margin=&#8221;2em||2em|1em|false|false&#8221; custom_padding=&#8221;|2em||0.5em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Incentivi Finanziari:<\/strong> Sconti massimi su contratti pluriennali e bonus per obiettivi.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x5c;||divi||400&#8243; icon_color=&#8221;#0c71c3&#8243; image_icon_background_color=&#8221;#FFFFFF&#8221; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;15px&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; body_line_height=&#8221;1.2em&#8221; image_icon_custom_margin=&#8221;2em||2em|1em|false|false&#8221; custom_padding=&#8221;|2em||0.5em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p data-local-id=\"bbab97748177\" data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\" data-pm-slice=\"1 1 [\"bulletList\",{\"localId\":\"b993606dd266\"},\"listItem\",{\"localId\":\"9a9d887977c7\"}]\"><strong data-prosemirror-content-type=\"mark\" data-prosemirror-mark-name=\"strong\">Ecosistema IA:<\/strong> Accesso al portale &#8220;IA Insider&#8221; e a un canale di webinar esclusivo sull&#8217;Intelligenza Artificiale applicata alla sicurezza scolastica.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x5c;||divi||400&#8243; icon_color=&#8221;#0c71c3&#8243; image_icon_background_color=&#8221;#FFFFFF&#8221; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;15px&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; body_line_height=&#8221;1.2em&#8221; image_icon_custom_margin=&#8221;2em||2em|1em|false|false&#8221; custom_padding=&#8221;|2em||0.5em|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Supporto &#8220;Guanto Bianco&#8221;:<\/strong> Implementazione assistita di IMTLazarus nei progetti pi\u00f9 critici.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Checklist di sicurezza Prepara la tua scuola per l&#8217;Intelligenza Artificiale L&#8217;IA \u00e8 gi\u00e0 nelle aule. Scarica la nostra Checklist di Implementazione Sicura e scopri come integrare questi strumenti garantendo il benessere digitale e il controllo del tuo ambiente educativo. &nbsp; Z Valutazione dei Rischi: Identifica e mitiga le minacce alla privacy e al cyberbullismo prima [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","content-type":"","inline_featured_image":false,"footnotes":""},"class_list":["post-3614","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Risorse dei partner - IMTLazarus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.imtlazarus.com\/recursos-de-partners\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Risorse dei partner - IMTLazarus\" \/>\n<meta property=\"og:description\" content=\"Checklist di sicurezza Prepara la tua scuola per l&#039;Intelligenza Artificiale L&#039;IA \u00e8 gi\u00e0 nelle aule. Scarica la nostra Checklist di Implementazione Sicura e scopri come integrare questi strumenti garantendo il benessere digitale e il controllo del tuo ambiente educativo. &nbsp; Z Valutazione dei Rischi: Identifica e mitiga le minacce alla privacy e al cyberbullismo prima [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.imtlazarus.com\/recursos-de-partners\/\" \/>\n<meta property=\"og:site_name\" content=\"IMTLazarus\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-03T10:59:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"22 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.imtlazarus.com\/recursos-de-partners\/\",\"url\":\"https:\/\/www.imtlazarus.com\/recursos-de-partners\/\",\"name\":\"Risorse dei partner - IMTLazarus\",\"isPartOf\":{\"@id\":\"https:\/\/www.imtlazarus.com\/#website\"},\"datePublished\":\"2024-04-28T13:38:20+00:00\",\"dateModified\":\"2026-06-03T10:59:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.imtlazarus.com\/recursos-de-partners\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.imtlazarus.com\/recursos-de-partners\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.imtlazarus.com\/recursos-de-partners\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.imtlazarus.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Risorse dei partner\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.imtlazarus.com\/#website\",\"url\":\"https:\/\/www.imtlazarus.com\/\",\"name\":\"IMTLazarus\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.imtlazarus.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Risorse dei partner - IMTLazarus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.imtlazarus.com\/recursos-de-partners\/","og_locale":"it_IT","og_type":"article","og_title":"Risorse dei partner - IMTLazarus","og_description":"Checklist di sicurezza Prepara la tua scuola per l'Intelligenza Artificiale L'IA \u00e8 gi\u00e0 nelle aule. Scarica la nostra Checklist di Implementazione Sicura e scopri come integrare questi strumenti garantendo il benessere digitale e il controllo del tuo ambiente educativo. &nbsp; Z Valutazione dei Rischi: Identifica e mitiga le minacce alla privacy e al cyberbullismo prima [&hellip;]","og_url":"https:\/\/www.imtlazarus.com\/recursos-de-partners\/","og_site_name":"IMTLazarus","article_modified_time":"2026-06-03T10:59:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"22 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.imtlazarus.com\/recursos-de-partners\/","url":"https:\/\/www.imtlazarus.com\/recursos-de-partners\/","name":"Risorse dei partner - IMTLazarus","isPartOf":{"@id":"https:\/\/www.imtlazarus.com\/#website"},"datePublished":"2024-04-28T13:38:20+00:00","dateModified":"2026-06-03T10:59:55+00:00","breadcrumb":{"@id":"https:\/\/www.imtlazarus.com\/recursos-de-partners\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.imtlazarus.com\/recursos-de-partners\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.imtlazarus.com\/recursos-de-partners\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.imtlazarus.com\/"},{"@type":"ListItem","position":2,"name":"Risorse dei partner"}]},{"@type":"WebSite","@id":"https:\/\/www.imtlazarus.com\/#website","url":"https:\/\/www.imtlazarus.com\/","name":"IMTLazarus","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.imtlazarus.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.imtlazarus.com\/it\/wp-json\/wp\/v2\/pages\/3614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.imtlazarus.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.imtlazarus.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.imtlazarus.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.imtlazarus.com\/it\/wp-json\/wp\/v2\/comments?post=3614"}],"version-history":[{"count":14,"href":"https:\/\/www.imtlazarus.com\/it\/wp-json\/wp\/v2\/pages\/3614\/revisions"}],"predecessor-version":[{"id":5725,"href":"https:\/\/www.imtlazarus.com\/it\/wp-json\/wp\/v2\/pages\/3614\/revisions\/5725"}],"wp:attachment":[{"href":"https:\/\/www.imtlazarus.com\/it\/wp-json\/wp\/v2\/media?parent=3614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}